{"id":7,"date":"2021-12-04T03:23:56","date_gmt":"2021-12-04T03:23:56","guid":{"rendered":"http:\/\/madenewhomes.com\/?page_id=7"},"modified":"2021-12-05T23:11:03","modified_gmt":"2021-12-05T23:11:03","slug":"contact","status":"publish","type":"page","link":"https:\/\/madenewhomes.com\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-block\" id=\"wpforms-69\"><form id=\"wpforms-form-69\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"69\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/7\" data-token=\"d343d86f093236b3bab2f16e05734055\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-69-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-69-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-69-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" required><\/div><div id=\"wpforms-69-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-69-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-69-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-69-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-69-field_2\">Message <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-69-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"69\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-69\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Get in Touch\" aria-live=\"assertive\" value=\"wpforms-submit\">Get in Touch<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/madenewhomes.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":5,"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":70,"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/pages\/7\/revisions\/70"}],"wp:attachment":[{"href":"https:\/\/madenewhomes.com\/index.php\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}